{"id":6152,"date":"2024-05-20T17:04:00","date_gmt":"2024-05-20T15:04:00","guid":{"rendered":"https:\/\/soritalia.com\/sori-at-tuttopizza-in-naples\/"},"modified":"2025-06-04T16:49:35","modified_gmt":"2025-06-04T14:49:35","slug":"sori-at-tuttopizza-in-naples","status":"publish","type":"post","link":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/","title":{"rendered":"Sor\u00ec at TUTTOPIZZA in Naples"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":4969,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":7,"footnotes":""},"categories":[73],"tags":[],"consigliato-per":[],"linea-industria":[],"linea-professionisti":[],"linea-retail":[],"prodotto":[],"prodotti-frozen":[],"class_list":["post-6152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-en"],"blocksy_meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sor\u00ec at TUTTOPIZZA in Naples - Sor\u00ec Italia srl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sor\u00ec at TUTTOPIZZA in Naples - Sor\u00ec Italia srl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/\" \/>\n<meta property=\"og:site_name\" content=\"Sor\u00ec Italia srl\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-20T15:04:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T14:49:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soritalia.com\/wp-content\/uploads\/2024\/09\/tuttopizza-maggio-24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"soritalia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"soritalia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/\"},\"author\":{\"name\":\"soritalia\",\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/#\\\/schema\\\/person\\\/fc314347cf38ad03b45549083a3c5089\"},\"headline\":\"Sor\u00ec at TUTTOPIZZA in Naples\",\"datePublished\":\"2024-05-20T15:04:00+00:00\",\"dateModified\":\"2025-06-04T14:49:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/\"},\"wordCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soritalia.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/tuttopizza-maggio-24.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/\",\"url\":\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/\",\"name\":\"Sor\u00ec at TUTTOPIZZA in Naples - Sor\u00ec Italia srl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soritalia.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/tuttopizza-maggio-24.jpg\",\"datePublished\":\"2024-05-20T15:04:00+00:00\",\"dateModified\":\"2025-06-04T14:49:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soritalia.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/tuttopizza-maggio-24.jpg\",\"contentUrl\":\"https:\\\/\\\/soritalia.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/tuttopizza-maggio-24.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"Sor\u00ec Italia al Cibus con il testimonial Franco Pepe e il conduttore Massimiliano Ossini - Sor\u00ec Italia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/sori-at-tuttopizza-in-naples\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/soritalia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sor\u00ec at TUTTOPIZZA in Naples\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/soritalia.com\\\/en\\\/\",\"name\":\"Sor\u00ec Italia\",\"description\":\"Produzioni casearie di Bufala Campana DOP dal 1868\",\"publisher\":{\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soritalia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/#organization\",\"name\":\"Sor\u00ec Italia\",\"url\":\"https:\\\/\\\/soritalia.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soritalia.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Sori-Italia-logo.svg\",\"contentUrl\":\"https:\\\/\\\/soritalia.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Sori-Italia-logo.svg\",\"width\":427,\"height\":390,\"caption\":\"Sor\u00ec Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/sori_italia\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/soritalia.com\\\/en\\\/#\\\/schema\\\/person\\\/fc314347cf38ad03b45549083a3c5089\",\"name\":\"soritalia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/soritalia.com\\\/wp-content\\\/litespeed\\\/avatar\\\/a72b8c2ddd3ce7441408205df82bded8.jpg?ver=1783705294\",\"url\":\"https:\\\/\\\/soritalia.com\\\/wp-content\\\/litespeed\\\/avatar\\\/a72b8c2ddd3ce7441408205df82bded8.jpg?ver=1783705294\",\"contentUrl\":\"https:\\\/\\\/soritalia.com\\\/wp-content\\\/litespeed\\\/avatar\\\/a72b8c2ddd3ce7441408205df82bded8.jpg?ver=1783705294\",\"caption\":\"soritalia\"},\"url\":\"https:\\\/\\\/soritalia.com\\\/en\\\/author\\\/soritalia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sor\u00ec at TUTTOPIZZA in Naples - Sor\u00ec Italia srl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/","og_locale":"en_US","og_type":"article","og_title":"Sor\u00ec at TUTTOPIZZA in Naples - Sor\u00ec Italia srl","og_url":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/","og_site_name":"Sor\u00ec Italia srl","article_published_time":"2024-05-20T15:04:00+00:00","article_modified_time":"2025-06-04T14:49:35+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/soritalia.com\/wp-content\/uploads\/2024\/09\/tuttopizza-maggio-24.jpg","type":"image\/jpeg"}],"author":"soritalia","twitter_card":"summary_large_image","twitter_misc":{"Written by":"soritalia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/#article","isPartOf":{"@id":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/"},"author":{"name":"soritalia","@id":"https:\/\/soritalia.com\/en\/#\/schema\/person\/fc314347cf38ad03b45549083a3c5089"},"headline":"Sor\u00ec at TUTTOPIZZA in Naples","datePublished":"2024-05-20T15:04:00+00:00","dateModified":"2025-06-04T14:49:35+00:00","mainEntityOfPage":{"@id":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/"},"wordCount":5,"publisher":{"@id":"https:\/\/soritalia.com\/en\/#organization"},"image":{"@id":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/#primaryimage"},"thumbnailUrl":"https:\/\/soritalia.com\/wp-content\/uploads\/2024\/09\/tuttopizza-maggio-24.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/","url":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/","name":"Sor\u00ec at TUTTOPIZZA in Naples - Sor\u00ec Italia srl","isPartOf":{"@id":"https:\/\/soritalia.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/#primaryimage"},"image":{"@id":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/#primaryimage"},"thumbnailUrl":"https:\/\/soritalia.com\/wp-content\/uploads\/2024\/09\/tuttopizza-maggio-24.jpg","datePublished":"2024-05-20T15:04:00+00:00","dateModified":"2025-06-04T14:49:35+00:00","breadcrumb":{"@id":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/#primaryimage","url":"https:\/\/soritalia.com\/wp-content\/uploads\/2024\/09\/tuttopizza-maggio-24.jpg","contentUrl":"https:\/\/soritalia.com\/wp-content\/uploads\/2024\/09\/tuttopizza-maggio-24.jpg","width":1080,"height":1080,"caption":"Sor\u00ec Italia al Cibus con il testimonial Franco Pepe e il conduttore Massimiliano Ossini - Sor\u00ec Italia"},{"@type":"BreadcrumbList","@id":"https:\/\/soritalia.com\/en\/sori-at-tuttopizza-in-naples\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/soritalia.com\/en\/"},{"@type":"ListItem","position":2,"name":"Sor\u00ec at TUTTOPIZZA in Naples"}]},{"@type":"WebSite","@id":"https:\/\/soritalia.com\/en\/#website","url":"https:\/\/soritalia.com\/en\/","name":"Sor\u00ec Italia","description":"Produzioni casearie di Bufala Campana DOP dal 1868","publisher":{"@id":"https:\/\/soritalia.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soritalia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/soritalia.com\/en\/#organization","name":"Sor\u00ec Italia","url":"https:\/\/soritalia.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/soritalia.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/soritalia.com\/wp-content\/uploads\/2024\/05\/Sori-Italia-logo.svg","contentUrl":"https:\/\/soritalia.com\/wp-content\/uploads\/2024\/05\/Sori-Italia-logo.svg","width":427,"height":390,"caption":"Sor\u00ec Italia"},"image":{"@id":"https:\/\/soritalia.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/sori_italia\/"]},{"@type":"Person","@id":"https:\/\/soritalia.com\/en\/#\/schema\/person\/fc314347cf38ad03b45549083a3c5089","name":"soritalia","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/soritalia.com\/wp-content\/litespeed\/avatar\/a72b8c2ddd3ce7441408205df82bded8.jpg?ver=1783705294","url":"https:\/\/soritalia.com\/wp-content\/litespeed\/avatar\/a72b8c2ddd3ce7441408205df82bded8.jpg?ver=1783705294","contentUrl":"https:\/\/soritalia.com\/wp-content\/litespeed\/avatar\/a72b8c2ddd3ce7441408205df82bded8.jpg?ver=1783705294","caption":"soritalia"},"url":"https:\/\/soritalia.com\/en\/author\/soritalia\/"}]}},"_links":{"self":[{"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/posts\/6152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/comments?post=6152"}],"version-history":[{"count":0,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/posts\/6152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/media\/4969"}],"wp:attachment":[{"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/media?parent=6152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/categories?post=6152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/tags?post=6152"},{"taxonomy":"consigliato-per","embeddable":true,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/consigliato-per?post=6152"},{"taxonomy":"linea-industria","embeddable":true,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/linea-industria?post=6152"},{"taxonomy":"linea-professionisti","embeddable":true,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/linea-professionisti?post=6152"},{"taxonomy":"linea-retail","embeddable":true,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/linea-retail?post=6152"},{"taxonomy":"prodotto","embeddable":true,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/prodotto?post=6152"},{"taxonomy":"prodotti-frozen","embeddable":true,"href":"https:\/\/soritalia.com\/en\/wp-json\/wp\/v2\/prodotti-frozen?post=6152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}